{"id":2139,"date":"2025-04-08T13:18:36","date_gmt":"2025-04-08T11:18:36","guid":{"rendered":"https:\/\/motonautika-luke.hr\/datenschutzerklaerung\/"},"modified":"2025-05-07T12:37:55","modified_gmt":"2025-05-07T10:37:55","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/motonautika-luke.hr\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2139\" class=\"elementor elementor-2139 elementor-968\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef409e e-flex e-con-boxed e-con e-parent\" data-id=\"7ef409e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5a287b elementor-widget elementor-widget-heading\" data-id=\"c5a287b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Datenschutzerkl\u00e4rung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-269fc8b elementor-widget elementor-widget-text-editor\" data-id=\"269fc8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Allgemeine Informationen<\/strong><\/p><p>Diese Datenschutzerkl\u00e4rung gilt f\u00fcr die Website <a href=\"https:\/\/motonautika-luke.hr\/\">https:\/\/motonautika-luke.hr\/<\/a>, die von der Firma <strong>MOTONAUTIKA-LUKE d.o.o.,<\/strong> Ulica Luke 38, 22243 Murter, Kroatien betrieben wird. Durch die Nutzung dieser Website best\u00e4tigen Sie, dass Sie die Bedingungen dieser Datenschutzerkl\u00e4rung gelesen, verstanden und akzeptiert haben. <\/p><p><strong>2. Verantwortlicher<\/strong><\/p><p>Verantwortlicher f\u00fcr die Verarbeitung personenbezogener Daten ist:<br><strong>MOTONAUTIKA-LUKE d.o.o.<\/strong><br>Ulica Luke 38, 22243 Murter, Hrvatska<br>OIB: <strong>77897531612<br><\/strong>Kontaktnummer: <strong>+385 98 198 4967<br><\/strong>E-mail: <strong>uprava@motonautika-luke.hr<\/strong><\/p><p><strong>3. Arten der von uns erhobenen Daten<\/strong><\/p><p>\u00dcber diese Website k\u00f6nnen folgende personenbezogene Daten erhoben werden:<\/p><ul><li>Vor- und Nachname (sofern vom Nutzer im Kontaktformular eingegeben)<\/li><li>E-Mail-Adresse und Telefonnummer<\/li><li>IP-Adresse sowie technische Informationen \u00fcber das verwendete Ger\u00e4t<\/li><li>Nutzungsdaten der Website (\u00fcber Cookies und Analyse-Tools)<\/li><\/ul><p>Die Daten werden ausschlie\u00dflich dann erhoben, wenn der Nutzer das Kontaktformular verwendet, der Nutzung von Cookies zustimmt oder mit interaktiven Elementen der Website interagiert.<\/p><p><strong>4. Zweck und Rechtsgrundlage der Datenverarbeitung<\/strong><\/p><p>Ihre Daten werden ausschlie\u00dflich zu folgenden Zwecken verarbeitet:<\/p><ul><li>Beantwortung von Anfragen \u00fcber das Kontaktformular<\/li><li>Betrieb, Schutz und Optimierung der Website<\/li><li>Statistische Auswertung der Besucherzahlen (anonym)<\/li><li>Darstellung des Standortes \u00fcber Google Maps<\/li><\/ul><p>Rechtsgrundlagen f\u00fcr die Verarbeitung sind Ihre Einwilligung, berechtigtes Interesse sowie gesetzliche Verpflichtungen.<\/p><p><strong>5. Cookies und Analyse<\/strong><\/p><p>Auf der Website verwenden wir Cookies, die f\u00fcr den Betrieb der Seite notwendig sind, sowie optionale Cookies f\u00fcr statistische Zwecke und zus\u00e4tzliche Funktionen.<br>Die Verwendung von Cookies wird \u00fcber ein Einwilligungsmanagement-System gesteuert, das es Ihnen erm\u00f6glicht, auszuw\u00e4hlen, welche Arten von Cookies Sie akzeptieren m\u00f6chten. <\/p><p>Sie k\u00f6nnen Ihre Einwilligung jederzeit \u00fcber die Option \u201eCookie-Einstellungen verwalten\u201c widerrufen oder \u00e4ndern.<\/p><p><strong>6. Sicherheit und technische Ma\u00dfnahmen<\/strong><\/p><p>Diese Website nutzt Sicherheitsma\u00dfnahmen zum Schutz vor sch\u00e4dlichen Inhalten und unbefugten Zugriffsversuchen. In bestimmten F\u00e4llen kann dabei die IP-Adresse des Nutzers vor\u00fcbergehend gespeichert werden, um verd\u00e4chtige Aktivit\u00e4ten zu erkennen. <\/p><p>Zudem kommen Tools zur Beschleunigung und Optimierung der Ladezeiten zum Einsatz, die keine personenbezogenen Daten der Nutzer erfassen.<\/p><p><strong>7. Google Maps<\/strong><\/p><p>Auf der Website ist eine Karte zur Anzeige des physischen Standorts des Unternehmens eingebettet.<br>Beim Laden der Karte kann Google bestimmte Daten erfassen (einschlie\u00dflich der IP-Adresse).<br>Die Karte wird erst angezeigt, nachdem der Nutzer der Darstellung von Inhalten Dritter \u00fcber das Cookie-Banner ausdr\u00fccklich zugestimmt hat.  <\/p><p>F\u00fcr weitere Informationen lesen Sie bitte die <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Google-Datenschutzerkl\u00e4rung<\/a> und die <a href=\"https:\/\/maps.google.com\/help\/terms_maps\/\" data-start=\"3600\" data-end=\"3663\" target=\"_blank\" rel=\"noopener\">Nutzungsbedingungen von Google Maps.<\/a><\/p><p><strong>8.Lokale Einbindung von Fonts<\/strong><\/p><p>Die Website verwendet lokal gespeicherte Schriftarten, wodurch eine \u00dcbermittlung von Daten an Dritte \u2013 wie etwa den Dienst Google Fonts \u2013 vermieden wird.<\/p><p><strong>9. Interaktive Elemente<\/strong><\/p><p>Telefonnummern und E-Mail-Adressen auf der Website sind als anklickbare Links gestaltet, um den Nutzern eine einfache Kontaktaufnahme zu erm\u00f6glichen.<br>Beim Anklicken wird die jeweils eigene Anwendung des Ger\u00e4ts verwendet (z.\u202fB. Telefon-App oder E-Mail-Client), ohne zus\u00e4tzliches Tracking. <\/p><p><strong>10. Ihre Rechte<\/strong><\/p><p>Gem\u00e4\u00df der Datenschutz-Grundverordnung (DSGVO) haben Sie das Recht:<\/p><ul><li>Auskunft \u00fcber die von uns verarbeiteten personenbezogenen Daten zu verlangen<\/li><li>die Berichtigung unrichtiger Daten zu beantragen<\/li><li>die L\u00f6schung Ihrer Daten zu fordern (\u201eRecht auf Vergessenwerden\u201c)<\/li><li>Widerspruch gegen die Verarbeitung einzulegen oder deren Einschr\u00e4nkung zu verlangen<\/li><li>Ihre Daten an einen anderen Verantwortlichen \u00fcbertragen zu lassen<\/li><\/ul><p>Zur Aus\u00fcbung dieser Rechte kontaktieren Sie uns bitte unter: <strong>uprava@motonautika-luke.hr<\/strong><\/p><p><strong>11. Datenspeicherung und -schutz<\/strong><\/p><p>Ihre Daten werden sicher gespeichert und durch technische sowie organisatorische Schutzma\u00dfnahmen gesichert. Der Zugriff auf personenbezogene Daten ist ausschlie\u00dflich autorisierten Personen vorbehalten. Eine Weitergabe an Dritte erfolgt nur mit Ihrer ausdr\u00fccklichen Einwilligung oder wenn dies gesetzlich vorgeschrieben ist. <\/p><p><strong>12. \u00c4nderungen der Datenschutzerkl\u00e4rung<\/strong><\/p><p>Wir behalten uns das Recht vor, diese Datenschutzerkl\u00e4rung an gesetzliche \u00c4nderungen oder neue Funktionen der Website anzupassen. Alle \u00c4nderungen werden auf dieser Seite deutlich kenntlich gemacht. <\/p><p><strong>Letzte Aktualisierung: 08. April 2025 <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung 1. Allgemeine Informationen Diese Datenschutzerkl\u00e4rung gilt f\u00fcr die Website https:\/\/motonautika-luke.hr\/, die von der Firma MOTONAUTIKA-LUKE d.o.o., Ulica Luke 38, 22243 Murter, Kroatien betrieben wird. Durch die Nutzung dieser Website best\u00e4tigen Sie, dass Sie die Bedingungen dieser Datenschutzerkl\u00e4rung gelesen, verstanden und akzeptiert haben. 2. Verantwortlicher Verantwortlicher f\u00fcr die Verarbeitung personenbezogener Daten ist:MOTONAUTIKA-LUKE d.o.o.Ulica Luke 38, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2139","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/comments?post=2139"}],"version-history":[{"count":3,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2139\/revisions"}],"predecessor-version":[{"id":2142,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2139\/revisions\/2142"}],"wp:attachment":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/media?parent=2139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}