{"id":2116,"date":"2025-04-07T14:45:35","date_gmt":"2025-04-07T12:45:35","guid":{"rendered":"https:\/\/motonautika-luke.hr\/volvo-penta\/"},"modified":"2025-05-12T09:53:36","modified_gmt":"2025-05-12T07:53:36","slug":"volvo-penta","status":"publish","type":"page","link":"https:\/\/motonautika-luke.hr\/de\/volvo-penta\/","title":{"rendered":"Volvo Penta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2116\" class=\"elementor elementor-2116 elementor-712\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdac2bf e-flex e-con-boxed e-con e-parent\" data-id=\"fdac2bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d62a2fd e-con-full e-flex e-con e-child\" data-id=\"d62a2fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-286e708 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"286e708\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Leistung der Sie vertrauen k\u00f6nnen<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07e9c45 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"07e9c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Volvo penta<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc6826 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4dc6826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"206\" data-end=\"498\">Volvo Penta ist weltweit als Synonym f\u00fcr Zuverl\u00e4ssigkeit, Innovation und technische Spitzenleistung in der maritimen Welt anerkannt.<br>Ihre Antriebssysteme werden auf Motorbooten, Yachten und professionellen Wasserfahrzeugen auf der ganzen Welt eingesetzt \u2013 und wir haben uns ganz bewusst und aus gutem Grund daf\u00fcr entschieden, uns ausschlie\u00dflich dieser Marke zu widmen. <\/p><p class=\"\" data-start=\"500\" data-end=\"679\">Als langj\u00e4hriger spezialisierter Partner bieten wir alles, was Sie f\u00fcr eine ruhige, sichere und effiziente Fahrt ben\u00f6tigen \u2013 von der Motorenauswahl und Installation bis hin zu Service, Wartung und Systemaustausch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f350662 e-flex e-con-boxed e-con e-parent\" data-id=\"f350662\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a72d7b e-con-full e-flex e-con e-child\" data-id=\"5a72d7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d7fab6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1d7fab6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7208a06 e-con-full e-flex e-con e-child\" data-id=\"7208a06\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9801b78 elementor-widget elementor-widget-heading\" data-id=\"9801b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum Volvo Penta?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ac1a95 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1ac1a95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"194\" data-end=\"523\">Wer sich f\u00fcr Volvo Penta entscheidet, setzt auf bew\u00e4hrte Technik, durchdachte Systeme und jahrzehntelange Erfahrung im maritimen Bereich. Der schwedische Hersteller gilt als einer der Vorreiter der Branche \u2013 nicht nur wegen der robusten Motoren, sondern auch dank intelligenter Gesamtl\u00f6sungen, die den Umgang mit dem Boot sp\u00fcrbar erleichtern und optimieren. <\/p><p class=\"\" data-start=\"525\" data-end=\"879\">Volvo Penta steht f\u00fcr ein perfekt abgestimmtes System: vom Antrieb \u00fcber Steuerung und K\u00fchlung bis hin zur elektronischen Integration. Alle Komponenten greifen nahtlos ineinander \u2013 f\u00fcr ein komfortables, stabiles und anpassungsf\u00e4higes Fahrerlebnis, unabh\u00e4ngig vom Bootstyp. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-212d84c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"212d84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"881\" data-end=\"945\"><strong>Was Volvo Penta Systeme so besonders macht:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2644bb4 e-con-full e-flex e-con e-child\" data-id=\"2644bb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3b6dd elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"cf3b6dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tZuverl\u00e4ssigkeit und Langlebigkeit unter allen Bedingungen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a31e5a elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9a31e5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEnergieeffizienz und reduzierter Kraftstoffverbrauch\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8b8a57 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f8b8a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLeiser, vibrationsarmer Betrieb mit intelligenter Steuerung\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3656f6 e-con-full e-flex e-con e-child\" data-id=\"d3656f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0e5ec8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e0e5ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEinfacher Service und gute Verf\u00fcgbarkeit von Originalteilen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc84054 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fc84054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKompatibilit\u00e4t mit unterschiedlichen Bootstypen und Systemen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d42d90 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7d42d90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-checkmark-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSystemintegration f\u00fcr einfache und effektive Bedienung\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b893cc8 e-flex e-con-boxed e-con e-parent\" data-id=\"b893cc8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0f9f942 e-con-full e-flex e-con e-child\" data-id=\"0f9f942\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-af00583 e-con-full e-flex e-con e-child\" data-id=\"af00583\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4fdcabd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4fdcabd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af8b5e9 elementor-widget elementor-widget-heading\" data-id=\"af8b5e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alles f\u00fcr Ihr Volvo Penta System<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f99f943 elementor-widget elementor-widget-text-editor\" data-id=\"f99f943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"252\" data-end=\"544\">Als autorisierter Service- und Vertriebspartner bieten wir alles, was Sie f\u00fcr einen stabilen und langfristigen Betrieb Ihres Volvo Penta Systems ben\u00f6tigen. Unser Service endet nicht beim Motor \u2013 wir k\u00fcmmern uns um alle relevanten Komponenten: Z-Antrieb, Saildrive, IPS, K\u00fchl- und Abgasanlagen, Elektronik und Steuerungssysteme. <\/p><p class=\"\" data-start=\"546\" data-end=\"627\">Wir begleiten Sie als technischer Partner \u2013 von der Planung bis zur laufenden Wartung:<\/p><p class=\"\" data-start=\"629\" data-end=\"937\">\u2714 Auswahl der passenden Ausr\u00fcstung je nach Boot und Nutzungsprofil<br data-start=\"691\" data-end=\"694\">\u2714 Beschaffung und Einbau originaler Volvo Penta Motoren und Ersatzteile<br data-start=\"755\" data-end=\"758\">\u2714 Repowering und Modernisierung von Antriebssystemen<br data-start=\"804\" data-end=\"807\">\u2714 Wartung, Reparaturen und Diagnostik nach Werksvorgaben<br data-start=\"869\" data-end=\"872\">\u2714 Technischer Support und schnelle Eins\u00e4tze vor Ort oder in unserer Werkstatt<\/p><p class=\"\" data-start=\"939\" data-end=\"1142\">Unser Servicezentrum in Murter ist vollst\u00e4ndig ausger\u00fcstet f\u00fcr Bootsanlagen, Notfallreparaturen und Arbeiten im Wasser. Alle Arbeiten werden pr\u00e4zise, fachgerecht und ohne Improvisation durchgef\u00fchrt \u2013 damit Ihr System zuverl\u00e4ssig funktioniert. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3a0b92 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"c3a0b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/ueber-uns\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LERNEN SIE UNS KENNEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0ee82a e-flex e-con-boxed e-con e-parent\" data-id=\"a0ee82a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-35636ad e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"35636ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-89efe43 e-con-full e-flex e-con e-child\" data-id=\"89efe43\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8120c5 elementor-widget elementor-widget-heading\" data-id=\"c8120c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Leistungen als autorisierter Volvo Penta Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb522a9 elementor-widget elementor-widget-text-editor\" data-id=\"eb522a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Als autorisiertes Volvo Penta Servicezentrum bieten wir ein umfassendes Leistungsspektrum \u2013 von pr\u00e4ziser Diagnostik und fachgerechtem Service bis hin zur Installation von Ausr\u00fcstung und kompletten Repowering-L\u00f6sungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee8a0b9 e-con-full e-flex e-con e-child\" data-id=\"ee8a0b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f533a5a e-con-full e-flex e-con e-child\" data-id=\"f533a5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ade72f9 e-con-full e-flex e-con e-child\" data-id=\"ade72f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1681809 elementor-flip-box--effect-slide elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"1681809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tools\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tVOLVO PENTA SERVICE\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tRegelm\u00e4\u00dfige Wartung, Fehlerdiagnose und Reparaturen von Volvo Penta Motoren \u2013 nach h\u00f6chsten Standards eines zertifizierten Servicepartners.\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/volvo-penta-service\/\">\n\t\t\t\t\t\t\tWeitere Infos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c7a934 e-con-full e-flex e-con e-child\" data-id=\"1c7a934\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e41c69d elementor-flip-box--effect-slide elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"e41c69d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-store-1\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tVOLVO PENTA VERTRIEB\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tWir liefern originale Volvo Penta Motoren, Antriebssysteme und Ersatzteile \u2013 mit professioneller Beratung bei Auswahl und Einbau.\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/volvo-penta-vertrieb\/\">\n\t\t\t\t\t\t\tWeitere Infos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8df4d6 e-con-full e-flex e-con e-child\" data-id=\"d8df4d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2c2fb85 e-con-full e-flex e-con e-child\" data-id=\"2c2fb85\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcc33b elementor-flip-box--effect-slide elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"2bcc33b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-page_search\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tINSPEKTION VON BOOTSMOTOREN UND ANTRIEBSSYSTEMEN\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tUmfassende technische \u00dcberpr\u00fcfung von Motor und Antrieb \u2013 inklusive Kompressionsmessung, Zylinderdruckverlustpr\u00fcfung, \u00d6l- und Ladedruckkontrolle sowie Diagnose der elektrischen Systeme. \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/inspektion-von-bootsmotoren-und-antriebssystemen\/\">\n\t\t\t\t\t\t\tWeitere Infos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6901e8d e-con-full e-flex e-con e-child\" data-id=\"6901e8d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38611cf elementor-flip-box--effect-slide elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"38611cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-Speed-Clock\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tVOLVO PENTA REPOWERING\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tWir ersetzen alte Motoren durch moderne Volvo Penta L\u00f6sungen \u2013 f\u00fcr bessere Effizienz, geringeren Verbrauch und langfristige Zuverl\u00e4ssigkeit.\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/volvo-penta-repowering\/\">\n\t\t\t\t\t\t\tWeitere Infos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c258e90 e-flex e-con-boxed e-con e-parent\" data-id=\"c258e90\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9fe760e e-con-full e-flex e-con e-child\" data-id=\"9fe760e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3eeee elementor-widget elementor-widget-heading\" data-id=\"2d3eeee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">M\u00f6chten Sie mehr erfahren? <\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7f2122 elementor-widget elementor-widget-heading\" data-id=\"a7f2122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wir sind f\u00fcr Sie da.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9a4d64 elementor-widget elementor-widget-text-editor\" data-id=\"a9a4d64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"2522\" data-end=\"2746\">Egal ob Sie ein neues System planen, einen alten Motor ersetzen oder einfach einen zuverl\u00e4ssigen Servicepartner suchen \u2013 sprechen Sie uns an.<br>Wir helfen Ihnen dabei, die beste Volvo Penta L\u00f6sung f\u00fcr Ihr Boot und Ihre Anforderungen zu finden.  <br>Bootfahren soll Freude machen \u2013 mit der richtigen Technik und dem passenden Partner wird es das auch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bed7b0 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5bed7b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/motonautika-luke.hr\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Leistung der Sie vertrauen k\u00f6nnen Volvo penta Volvo Penta ist weltweit als Synonym f\u00fcr Zuverl\u00e4ssigkeit, Innovation und technische Spitzenleistung in der maritimen Welt anerkannt.Ihre Antriebssysteme werden auf Motorbooten, Yachten und professionellen Wasserfahrzeugen auf der ganzen Welt eingesetzt \u2013 und wir haben uns ganz bewusst und aus gutem Grund daf\u00fcr entschieden, uns ausschlie\u00dflich dieser Marke zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2116","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/comments?post=2116"}],"version-history":[{"count":5,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2116\/revisions"}],"predecessor-version":[{"id":2233,"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/pages\/2116\/revisions\/2233"}],"wp:attachment":[{"href":"https:\/\/motonautika-luke.hr\/de\/wp-json\/wp\/v2\/media?parent=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}